
















{"id":1271,"date":"2018-09-27T13:51:39","date_gmt":"2018-09-27T13:51:39","guid":{"rendered":"http:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/"},"modified":"2018-09-27T13:51:39","modified_gmt":"2018-09-27T13:51:39","slug":"hackney-central-library-central-lending-1950","status":"publish","type":"post","link":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/","title":{"rendered":"Hackney Central Library. Central Lending. 1950."},"content":{"rendered":"<p>Mare Street and Paragon Road, Hackney<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mare Street and Paragon Road, Hackney<\/p>\n","protected":false},"author":1,"featured_media":213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[24,12,126,61],"tags":[],"class_list":["post-1271","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-1950s","category-buildings","category-libraries","category-mare-street-and-paragon-road"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hackney Central Library. Central Lending. 1950. - Hackney Photos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hackney Central Library. Central Lending. 1950. - Hackney Photos\" \/>\n<meta property=\"og:description\" content=\"Mare Street and Paragon Road, Hackney\" \/>\n<meta property=\"og:url\" content=\"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/\" \/>\n<meta property=\"og:site_name\" content=\"Hackney Photos\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-27T13:51:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/boroughphotos.org\/hackney\/wp-content\/uploads\/2018\/09\/P00210.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"925\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"hackney2017\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"hackney2017\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/\"},\"author\":{\"name\":\"hackney2017\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/#\\\/schema\\\/person\\\/5388c37a13094fbb3d374ab944c48ff9\"},\"headline\":\"Hackney Central Library. Central Lending. 1950.\",\"datePublished\":\"2018-09-27T13:51:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/\"},\"wordCount\":11,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/P00210.jpg\",\"articleSection\":[\"1950s\",\"Buildings\",\"Libraries\",\"Mare Street and Paragon Road\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/\",\"url\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/\",\"name\":\"Hackney Central Library. Central Lending. 1950. - Hackney Photos\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/P00210.jpg\",\"datePublished\":\"2018-09-27T13:51:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/#\\\/schema\\\/person\\\/5388c37a13094fbb3d374ab944c48ff9\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#primaryimage\",\"url\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/P00210.jpg\",\"contentUrl\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/P00210.jpg\",\"width\":1280,\"height\":925},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/hackney-central-library-central-lending-1950\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hackney Central Library. Central Lending. 1950.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/#website\",\"url\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/\",\"name\":\"Hackney Photos\",\"description\":\"Photos from The Hackney Borough Archives\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/boroughphotos.org\\\/hackney\\\/#\\\/schema\\\/person\\\/5388c37a13094fbb3d374ab944c48ff9\",\"name\":\"hackney2017\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/987e462264a629c68ce8c42f091da6850a449db5ba9b29f18e8384966ca09818?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/987e462264a629c68ce8c42f091da6850a449db5ba9b29f18e8384966ca09818?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/987e462264a629c68ce8c42f091da6850a449db5ba9b29f18e8384966ca09818?s=96&d=mm&r=g\",\"caption\":\"hackney2017\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hackney Central Library. Central Lending. 1950. - Hackney Photos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/","og_locale":"en_GB","og_type":"article","og_title":"Hackney Central Library. Central Lending. 1950. - Hackney Photos","og_description":"Mare Street and Paragon Road, Hackney","og_url":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/","og_site_name":"Hackney Photos","article_published_time":"2018-09-27T13:51:39+00:00","og_image":[{"width":1280,"height":925,"url":"https:\/\/boroughphotos.org\/hackney\/wp-content\/uploads\/2018\/09\/P00210.jpg","type":"image\/jpeg"}],"author":"hackney2017","twitter_card":"summary_large_image","twitter_misc":{"Written by":"hackney2017"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#article","isPartOf":{"@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/"},"author":{"name":"hackney2017","@id":"https:\/\/boroughphotos.org\/hackney\/#\/schema\/person\/5388c37a13094fbb3d374ab944c48ff9"},"headline":"Hackney Central Library. Central Lending. 1950.","datePublished":"2018-09-27T13:51:39+00:00","mainEntityOfPage":{"@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/"},"wordCount":11,"commentCount":0,"image":{"@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#primaryimage"},"thumbnailUrl":"https:\/\/boroughphotos.org\/hackney\/wp-content\/uploads\/2018\/09\/P00210.jpg","articleSection":["1950s","Buildings","Libraries","Mare Street and Paragon Road"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/","url":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/","name":"Hackney Central Library. Central Lending. 1950. - Hackney Photos","isPartOf":{"@id":"https:\/\/boroughphotos.org\/hackney\/#website"},"primaryImageOfPage":{"@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#primaryimage"},"image":{"@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#primaryimage"},"thumbnailUrl":"https:\/\/boroughphotos.org\/hackney\/wp-content\/uploads\/2018\/09\/P00210.jpg","datePublished":"2018-09-27T13:51:39+00:00","author":{"@id":"https:\/\/boroughphotos.org\/hackney\/#\/schema\/person\/5388c37a13094fbb3d374ab944c48ff9"},"breadcrumb":{"@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#primaryimage","url":"https:\/\/boroughphotos.org\/hackney\/wp-content\/uploads\/2018\/09\/P00210.jpg","contentUrl":"https:\/\/boroughphotos.org\/hackney\/wp-content\/uploads\/2018\/09\/P00210.jpg","width":1280,"height":925},{"@type":"BreadcrumbList","@id":"https:\/\/boroughphotos.org\/hackney\/hackney-central-library-central-lending-1950\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/boroughphotos.org\/hackney\/"},{"@type":"ListItem","position":2,"name":"Hackney Central Library. Central Lending. 1950."}]},{"@type":"WebSite","@id":"https:\/\/boroughphotos.org\/hackney\/#website","url":"https:\/\/boroughphotos.org\/hackney\/","name":"Hackney Photos","description":"Photos from The Hackney Borough Archives","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/boroughphotos.org\/hackney\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/boroughphotos.org\/hackney\/#\/schema\/person\/5388c37a13094fbb3d374ab944c48ff9","name":"hackney2017","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/987e462264a629c68ce8c42f091da6850a449db5ba9b29f18e8384966ca09818?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/987e462264a629c68ce8c42f091da6850a449db5ba9b29f18e8384966ca09818?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/987e462264a629c68ce8c42f091da6850a449db5ba9b29f18e8384966ca09818?s=96&d=mm&r=g","caption":"hackney2017"}}]}},"_links":{"self":[{"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/posts\/1271","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/comments?post=1271"}],"version-history":[{"count":0,"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/posts\/1271\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/media\/213"}],"wp:attachment":[{"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/media?parent=1271"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/categories?post=1271"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/boroughphotos.org\/hackney\/wp-json\/wp\/v2\/tags?post=1271"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}